{"id":235291,"date":"2019-06-06T10:33:49","date_gmt":"2019-06-06T08:33:49","guid":{"rendered":"https:\/\/open2digital.com\/expertises\/cm-spain-portugal\/"},"modified":"2025-01-02T17:29:14","modified_gmt":"2025-01-02T16:29:14","slug":"cm-spain-portugal","status":"publish","type":"expertises","link":"https:\/\/open2digital.com\/en\/expertises\/cm-spain-portugal\/","title":{"rendered":"CM Spain &amp; Portugal"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"tags":[],"class_list":["post-235291","expertises","type-expertises","status-publish","format-standard","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Expand your presence in Spain and Portugal with our community manager. Engage local audiences with tailored content and strategies.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Open2Digital\"\/>\n\t<meta name=\"google-site-verification\" content=\"Ff_YQYZjkRypB-1KsVcpxXeEkgUyNrIyqrZY5VjCkVM\" \/>\n\t<meta name=\"keywords\" content=\"community manager spain,digital agency spain,community manager portugal,digital agency portugal,digital agency,digital marketing,digital marketing agency,community management,community manager,digital agency europe,digital agency france,digital agency paris,social media manager,digital marketing agency europe\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/open2digital.com\/en\/expertises\/cm-spain-portugal\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Open2Digital\" \/>\n\t\t<meta property=\"og:type\" content=\"activity\" \/>\n\t\t<meta property=\"og:title\" content=\"Community Manager for Spain &amp; Portugal | Open2Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"Expand your presence in Spain and Portugal with our community manager. Engage local audiences with tailored content and strategies.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/open2digital.com\/en\/expertises\/cm-spain-portugal\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/open2digital.com\/wp-content\/uploads\/2023\/02\/03_Expertises_Secteur_Mode.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/open2digital.com\/wp-content\/uploads\/2023\/02\/03_Expertises_Secteur_Mode.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@Open2Europe\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Community Manager for Spain &amp; Portugal | Open2Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Expand your presence in Spain and Portugal with our community manager. Engage local audiences with tailored content and strategies.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/open2digital.com\/wp-content\/uploads\/2023\/02\/03_Expertises_Secteur_Mode.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/open2digital.com\\\/en\\\/expertises\\\/cm-spain-portugal\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/open2digital.com\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/open2digital.com\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/open2digital.com\\\/en\\\/expertises\\\/cm-spain-portugal\\\/#listItem\",\"name\":\"CM Spain &amp; Portugal\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/open2digital.com\\\/en\\\/expertises\\\/cm-spain-portugal\\\/#listItem\",\"position\":2,\"name\":\"CM Spain &amp; Portugal\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/open2digital.com\\\/en\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/open2digital.com\\\/en\\\/#organization\",\"name\":\"Open2Digital by Open2Europe\",\"description\":\"Agence digitale sp\\u00e9cialiste des m\\u00e9dias sociaux.\",\"url\":\"https:\\\/\\\/open2digital.com\\\/en\\\/\",\"email\":\"contact@open2digital.com\",\"telephone\":\"+33155021453\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/open2digital.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo_Open2digital86363.png\",\"@id\":\"https:\\\/\\\/open2digital.com\\\/en\\\/expertises\\\/cm-spain-portugal\\\/#organizationLogo\",\"width\":842,\"height\":595,\"caption\":\"Open2Digital Logo\"},\"image\":{\"@id\":\"https:\\\/\\\/open2digital.com\\\/en\\\/expertises\\\/cm-spain-portugal\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/open2europe\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@open2digital\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/open2europe\\\/\"],\"address\":{\"@id\":\"https:\\\/\\\/open2digital.com\\\/en\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"63-65 Avenue Gabriel P\\u00e9ri\",\"postalCode\":\"92600\",\"addressLocality\":\"Asni\\u00e8res-sur-Seine\",\"addressCountry\":\"FR\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/open2digital.com\\\/en\\\/author\\\/pgonzalez-trejo_v878kbkh\\\/#author\",\"url\":\"https:\\\/\\\/open2digital.com\\\/en\\\/author\\\/pgonzalez-trejo_v878kbkh\\\/\",\"name\":\"Open2Digital\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/open2digital.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Petits-Agences-96x96.jpg\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/open2digital.com\\\/en\\\/expertises\\\/cm-spain-portugal\\\/#webpage\",\"url\":\"https:\\\/\\\/open2digital.com\\\/en\\\/expertises\\\/cm-spain-portugal\\\/\",\"name\":\"Community Manager for Spain & Portugal | Open2Digital\",\"description\":\"Expand your presence in Spain and Portugal with our community manager. Engage local audiences with tailored content and strategies.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/open2digital.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/open2digital.com\\\/en\\\/expertises\\\/cm-spain-portugal\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/open2digital.com\\\/en\\\/author\\\/pgonzalez-trejo_v878kbkh\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/open2digital.com\\\/en\\\/author\\\/pgonzalez-trejo_v878kbkh\\\/#author\"},\"datePublished\":\"2019-06-06T10:33:49+02:00\",\"dateModified\":\"2025-01-02T17:29:14+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/open2digital.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/open2digital.com\\\/en\\\/\",\"name\":\"Open2Digital\",\"alternateName\":\"O2D\",\"description\":\"Agence digitale sp\\u00e9cialiste des m\\u00e9dias sociaux.\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/open2digital.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Community Manager for Spain &amp; Portugal | Open2Digital<\/title>\n\n","aioseo_head_json":{"title":"Community Manager for Spain & Portugal | Open2Digital","description":"Expand your presence in Spain and Portugal with our community manager. Engage local audiences with tailored content and strategies.","canonical_url":"https:\/\/open2digital.com\/en\/expertises\/cm-spain-portugal\/","robots":"max-image-preview:large","keywords":"community manager spain,digital agency spain,community manager portugal,digital agency portugal,digital agency,digital marketing,digital marketing agency,community management,community manager,digital agency europe,digital agency france,digital agency paris,social media manager,digital marketing agency europe","webmasterTools":{"google-site-verification":"Ff_YQYZjkRypB-1KsVcpxXeEkgUyNrIyqrZY5VjCkVM","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/open2digital.com\/en\/expertises\/cm-spain-portugal\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/open2digital.com\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/open2digital.com\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/open2digital.com\/en\/expertises\/cm-spain-portugal\/#listItem","name":"CM Spain &amp; Portugal"}},{"@type":"ListItem","@id":"https:\/\/open2digital.com\/en\/expertises\/cm-spain-portugal\/#listItem","position":2,"name":"CM Spain &amp; Portugal","previousItem":{"@type":"ListItem","@id":"https:\/\/open2digital.com\/en\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/open2digital.com\/en\/#organization","name":"Open2Digital by Open2Europe","description":"Agence digitale sp\u00e9cialiste des m\u00e9dias sociaux.","url":"https:\/\/open2digital.com\/en\/","email":"contact@open2digital.com","telephone":"+33155021453","logo":{"@type":"ImageObject","url":"https:\/\/open2digital.com\/wp-content\/uploads\/2023\/04\/Logo_Open2digital86363.png","@id":"https:\/\/open2digital.com\/en\/expertises\/cm-spain-portugal\/#organizationLogo","width":842,"height":595,"caption":"Open2Digital Logo"},"image":{"@id":"https:\/\/open2digital.com\/en\/expertises\/cm-spain-portugal\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/open2europe\/","https:\/\/www.tiktok.com\/@open2digital","https:\/\/www.linkedin.com\/company\/open2europe\/"],"address":{"@id":"https:\/\/open2digital.com\/en\/#postaladdress","@type":"PostalAddress","streetAddress":"63-65 Avenue Gabriel P\u00e9ri","postalCode":"92600","addressLocality":"Asni\u00e8res-sur-Seine","addressCountry":"FR"}},{"@type":"Person","@id":"https:\/\/open2digital.com\/en\/author\/pgonzalez-trejo_v878kbkh\/#author","url":"https:\/\/open2digital.com\/en\/author\/pgonzalez-trejo_v878kbkh\/","name":"Open2Digital","image":{"@type":"ImageObject","url":"https:\/\/open2digital.com\/wp-content\/uploads\/2021\/11\/Petits-Agences-96x96.jpg"}},{"@type":"WebPage","@id":"https:\/\/open2digital.com\/en\/expertises\/cm-spain-portugal\/#webpage","url":"https:\/\/open2digital.com\/en\/expertises\/cm-spain-portugal\/","name":"Community Manager for Spain & Portugal | Open2Digital","description":"Expand your presence in Spain and Portugal with our community manager. Engage local audiences with tailored content and strategies.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/open2digital.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/open2digital.com\/en\/expertises\/cm-spain-portugal\/#breadcrumblist"},"author":{"@id":"https:\/\/open2digital.com\/en\/author\/pgonzalez-trejo_v878kbkh\/#author"},"creator":{"@id":"https:\/\/open2digital.com\/en\/author\/pgonzalez-trejo_v878kbkh\/#author"},"datePublished":"2019-06-06T10:33:49+02:00","dateModified":"2025-01-02T17:29:14+01:00"},{"@type":"WebSite","@id":"https:\/\/open2digital.com\/en\/#website","url":"https:\/\/open2digital.com\/en\/","name":"Open2Digital","alternateName":"O2D","description":"Agence digitale sp\u00e9cialiste des m\u00e9dias sociaux.","inLanguage":"en-US","publisher":{"@id":"https:\/\/open2digital.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Open2Digital","og:type":"activity","og:title":"Community Manager for Spain &amp; Portugal | Open2Digital","og:description":"Expand your presence in Spain and Portugal with our community manager. Engage local audiences with tailored content and strategies.","og:url":"https:\/\/open2digital.com\/en\/expertises\/cm-spain-portugal\/","og:image":"https:\/\/open2digital.com\/wp-content\/uploads\/2023\/02\/03_Expertises_Secteur_Mode.png","og:image:secure_url":"https:\/\/open2digital.com\/wp-content\/uploads\/2023\/02\/03_Expertises_Secteur_Mode.png","og:image:width":1080,"og:image:height":1080,"twitter:card":"summary","twitter:site":"@Open2Europe","twitter:title":"Community Manager for Spain &amp; Portugal | Open2Digital","twitter:description":"Expand your presence in Spain and Portugal with our community manager. Engage local audiences with tailored content and strategies.","twitter:image":"https:\/\/open2digital.com\/wp-content\/uploads\/2023\/02\/03_Expertises_Secteur_Mode.png"},"aioseo_meta_data":{"post_id":"235291","title":"Community Manager for Spain &amp; Portugal #separator_sa #site_title","description":"Expand your presence in Spain and Portugal with our community manager. Engage local audiences with tailored content and strategies.","keywords":[{"label":"community manager spain","value":"community manager spain"},{"label":"digital agency spain","value":"digital agency spain"},{"label":"community manager portugal","value":"community manager portugal"},{"label":"digital agency portugal","value":"digital agency portugal"},{"label":"digital agency","value":"digital agency"},{"label":"digital marketing","value":"digital marketing"},{"label":"digital marketing agency","value":"digital marketing agency"},{"label":"community management","value":"community management"},{"label":"community manager","value":"community manager"},{"label":"digital agency europe","value":"digital agency europe"},{"label":"digital agency france","value":"digital agency france"},{"label":"digital agency paris","value":"digital agency paris"},{"label":"social media manager","value":"social media manager"},{"label":"digital marketing agency europe","value":"digital marketing agency europe"}],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"activity","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"summary","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-05-13 07:28:55","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2024-11-25 12:15:48","updated":"2026-05-13 07:28:55"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/open2digital.com\/en\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tCM Spain &amp; Portugal\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/open2digital.com\/en\/"},{"label":"CM Spain &amp; Portugal","link":"https:\/\/open2digital.com\/en\/expertises\/cm-spain-portugal\/"}],"_links":{"self":[{"href":"https:\/\/open2digital.com\/en\/wp-json\/wp\/v2\/expertises\/235291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/open2digital.com\/en\/wp-json\/wp\/v2\/expertises"}],"about":[{"href":"https:\/\/open2digital.com\/en\/wp-json\/wp\/v2\/types\/expertises"}],"author":[{"embeddable":true,"href":"https:\/\/open2digital.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/open2digital.com\/en\/wp-json\/wp\/v2\/expertises\/235291\/revisions"}],"predecessor-version":[{"id":235547,"href":"https:\/\/open2digital.com\/en\/wp-json\/wp\/v2\/expertises\/235291\/revisions\/235547"}],"wp:attachment":[{"href":"https:\/\/open2digital.com\/en\/wp-json\/wp\/v2\/media?parent=235291"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/open2digital.com\/en\/wp-json\/wp\/v2\/tags?post=235291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}